{"id":10631,"date":"2026-01-27T10:18:01","date_gmt":"2026-01-27T09:18:01","guid":{"rendered":"https:\/\/www.euronat.com\/hebergement-vente\/11-albizzias\/"},"modified":"2026-07-01T12:50:29","modified_gmt":"2026-07-01T10:50:29","slug":"11-albizzias","status":"publish","type":"hebergement-vente","link":"https:\/\/www.euronat.com\/en\/accommodation-sales\/11-albizzias\/","title":{"rendered":"11 Albizzias"},"content":{"rendered":"\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-1676a2cc wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--30)\">\n<p class=\"has-text-align-center has-accent-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.625), 20px);line-height:1;text-transform:uppercase\">mobile homes for sale<\/p>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center has-contrast-2-color has-text-color has-link-color wp-elements-2\" style=\"font-size:clamp(44.14px, 2.759rem + ((1vw - 3.2px) * 4.256), 85px);line-height:1;text-transform:none\">11 Albizzias<\/h1>\n\n\n\n<p class=\"has-text-align-center has-contrast-3-color has-text-color has-link-color wp-elements-3 wp-block-paragraph\" style=\"font-size:clamp(21.536px, 1.346rem + ((1vw - 3.2px) * 1.403), 35px);line-height:1;text-transform:uppercase\"><strong>O&#8217;TINY 830<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-layout-flex wp-container-core-group-is-layout-38f34b17 wp-block-group-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-group rg-superficies is-nowrap is-layout-flex wp-container-core-group-is-layout-3a5e8263 wp-block-group-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"42\" height=\"42\" src=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/euronat-m2.png\" alt=\"euronat m2\" class=\"wp-image-6760\" style=\"width:20px\"\/><\/figure>\n\n\n<div style=\"font-size:clamp(15.197px, 0.95rem + ((1vw - 3.2px) * 0.813), 23px)\" class=\"taxonomy-gt-vente-superficie has-link-color wp-elements-4 wp-block-post-terms has-text-color has-contrast-color\"><span class=\"wp-block-post-terms__prefix\"> <\/span><span>33<\/span><\/div>\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:clamp(15.197px, 0.95rem + ((1vw - 3.2px) * 0.813), 23px);\">m\u00b2<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group rg-capacity is-nowrap is-layout-flex wp-container-core-group-is-layout-31596b0d wp-block-group-is-layout-flex\" style=\"border-top-style:none;border-top-width:0px;border-right-color:#1b1b1b80;border-right-width:1px;border-bottom-style:none;border-bottom-width:0px;border-left-color:#1b1b1b80;border-left-width:1px;padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<figure class=\"wp-block-image size-full is-resized wp-duotone-174e4c-ffffff-1\"><img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/porte-ouverte.svg\" alt=\"porte ouverte\" class=\"wp-image-13958\" style=\"width:20px\"\/><\/figure>\n\n\n<div style=\"font-size:clamp(15.197px, 0.95rem + ((1vw - 3.2px) * 0.813), 23px)\" class=\"taxonomy-gt-vente-nombre-chambres has-link-color wp-elements-5 wp-block-post-terms has-text-color has-contrast-color\"><span>2<\/span><\/div>\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:clamp(15.197px, 0.95rem + ((1vw - 3.2px) * 0.813), 23px);\">rm.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group rg-sdb is-nowrap is-layout-flex wp-container-core-group-is-layout-3a5e8263 wp-block-group-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<figure class=\"wp-block-image size-full is-resized is-style-default\"><img decoding=\"async\" width=\"42\" height=\"42\" src=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/euronat-douche.png\" alt=\"euronat shower\" class=\"wp-image-6762\" style=\"width:20px\"\/><\/figure>\n\n\n<div style=\"font-size:clamp(15.197px, 0.95rem + ((1vw - 3.2px) * 0.813), 23px)\" class=\"taxonomy-gt-vente-nombre-sdb has-link-color wp-elements-6 wp-block-post-terms has-text-color has-contrast-color\"><span>1<\/span><\/div>\n\n\n<p class=\"has-contrast-color has-text-color has-link-color wp-elements-7 wp-block-paragraph\" style=\"font-size:clamp(15.197px, 0.95rem + ((1vw - 3.2px) * 0.813), 23px);\">bath<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center cols-photos is-layout-flex wp-container-core-columns-is-layout-3a88641f wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:57%\">\n<figure class=\"wp-block-image size-full has-custom-border\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-entree.jpg\" alt=\"Euronatimmo 11 Albizzias entrance\" class=\"wp-image-7539\" style=\"border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-left-radius:30px;border-bottom-right-radius:30px;aspect-ratio:16\/9;object-fit:cover\" srcset=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-entree.jpg 1024w, https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-entree-300x225.jpg 300w, https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-entree-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:43%\">\n<div style=\"--gt-vente-galerie-border-radius: 30px;--gt-vente-galerie-gap: 0.6em\" class=\"gt-vente-galerie gt-vente-galerie--columns-2 gt-vente-galerie--aspect-4-3 wp-block-gt-gt-fse-vente-galerie\" data-gt-vente-galerie=\"true\">\n    <div class=\"gt-vente-galerie__grid\" style=\"gap: 0.6em;\">\n                    <div class=\"gt-vente-galerie__item\" style=\"border-radius: 30px;\">\n                <a href=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-chambre.jpg\" \n                   class=\"gt-vente-galerie__link\" \n                   data-fancybox=\"gt-vente-galerie\"\n                   data-caption=\"\"\n                   data-src=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-chambre.jpg\">\n                    <div class=\"gt-vente-galerie__image-wrapper\">\n                                                    <img decoding=\"async\" width=\"1024\" height=\"771\" src=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-chambre.jpg\" class=\"gt-vente-galerie__image\" alt=\"Euronatimmo 11 Albizzias chambre\" srcset=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-chambre.jpg 1024w, https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-chambre-300x226.jpg 300w, https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-chambre-768x578.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>                                                                    <\/div>\n                <\/a>\n            <\/div>\n                    <div class=\"gt-vente-galerie__item\" style=\"border-radius: 30px;\">\n                <a href=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-chambre-.jpg\" \n                   class=\"gt-vente-galerie__link\" \n                   data-fancybox=\"gt-vente-galerie\"\n                   data-caption=\"\"\n                   data-src=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-chambre-.jpg\">\n                    <div class=\"gt-vente-galerie__image-wrapper\">\n                                                    <img decoding=\"async\" width=\"1024\" height=\"771\" src=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-chambre-.jpg\" class=\"gt-vente-galerie__image\" alt=\"Euronatimmo 11 Albizzias chambre\" srcset=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-chambre-.jpg 1024w, https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-chambre--300x226.jpg 300w, https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-chambre--768x578.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>                                                                    <\/div>\n                <\/a>\n            <\/div>\n                    <div class=\"gt-vente-galerie__item\" style=\"border-radius: 30px;\">\n                <a href=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-salon.jpg\" \n                   class=\"gt-vente-galerie__link\" \n                   data-fancybox=\"gt-vente-galerie\"\n                   data-caption=\"\"\n                   data-src=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-salon.jpg\">\n                    <div class=\"gt-vente-galerie__image-wrapper\">\n                                                    <img decoding=\"async\" width=\"1024\" height=\"771\" src=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-salon.jpg\" class=\"gt-vente-galerie__image\" alt=\"Euronatimmo 11 Albizzias salon\" srcset=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-salon.jpg 1024w, https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-salon-300x226.jpg 300w, https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-salon-768x578.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>                                                                    <\/div>\n                <\/a>\n            <\/div>\n                    <div class=\"gt-vente-galerie__item\" style=\"border-radius: 30px;\">\n                <a href=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-sejour.jpg\" \n                   class=\"gt-vente-galerie__link\" \n                   data-fancybox=\"gt-vente-galerie\"\n                   data-caption=\"\"\n                   data-src=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-sejour.jpg\">\n                    <div class=\"gt-vente-galerie__image-wrapper\">\n                                                    <img decoding=\"async\" width=\"1024\" height=\"771\" src=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-sejour.jpg\" class=\"gt-vente-galerie__image\" alt=\"Euronatimmo 11 Albizzias sejour\" srcset=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-sejour.jpg 1024w, https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-sejour-300x226.jpg 300w, https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-sejour-768x578.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>                                                                            <div class=\"gt-vente-galerie__more-indicator\">\n                                <span class=\"gt-vente-galerie__more-icon\">+<\/span>\n                                <span class=\"gt-vente-galerie__more-count\">1<\/span>\n                            <\/div>\n                                            <\/div>\n                <\/a>\n            <\/div>\n            <\/div>\n    \n            <div class=\"gt-vente-galerie__hidden\" style=\"display: none;\">\n                            <a href=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-terrasse.jpg\" \n                   data-fancybox=\"gt-vente-galerie\"\n                   data-caption=\"\"\n                   data-src=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-terrasse.jpg\">\n                <\/a>\n                    <\/div>\n    <\/div>\n\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-top:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-3a88641f wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:57%\">\n<p class=\"has-accent-5-color has-text-color has-link-color has-molentta-font-family wp-elements-8 wp-block-paragraph\" style=\"font-size:clamp(21.536px, 1.346rem + ((1vw - 3.2px) * 1.403), 35px);\">Description<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.313), 17px);\">Don&#8217;t wait to discover this 2007 mobile home, approx. 33 m\u00b2, with living room and open kitchen, two bedrooms and shower room with toilet.<br\/>Its large enclosed terrace offers a real extra space to enjoy the outdoors in any season.<br\/>Annual rent 2026: \u20ac3,510.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agency fees<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-style:normal;font-weight:700\"><\/p>\n\n\n\n<div class=\"wp-block-group is-content-justification-left is-layout-flex wp-container-core-group-is-layout-c698a761 wp-block-group-is-layout-flex\" style=\"padding-top:var(--wp--preset--spacing--30)\"><div style=\"font-size:clamp(19.481px, 1.218rem + ((1vw - 3.2px) * 1.2), 31px);font-style:normal;font-weight:700;border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-left-radius:50px;border-bottom-right-radius:50px;padding-top:23px;padding-bottom:23px;padding-left:52px;padding-right:52px\" class=\"taxonomy-gt-vente-prix has-link-color wp-elements-9 wp-block-post-terms has-text-color has-base-color has-background has-accent-background-color\"><span>43 000 \u20ac<\/span><\/div>\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-center is-layout-flex wp-container-core-group-is-layout-1917e900 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-buttons btn-vert animated fadeIn slow is-content-justification-left is-layout-flex wp-container-core-buttons-is-layout-1a6b9481 wp-block-buttons-is-layout-flex\" style=\"padding-top:0\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/EURONATIMMO-BAREME.pdf\" style=\"border-top-left-radius:100px;border-top-right-radius:100px;border-bottom-left-radius:100px;border-bottom-right-radius:100px;padding-top:14px;padding-right:32px;padding-bottom:14px;padding-left:32px;text-transform:uppercase\" target=\"_blank\" rel=\"noreferrer noopener\">Our rates<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><em>Fees at seller&#8217;s expense<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:43%\">\n<div class=\"wp-block-group has-background has-global-padding is-layout-constrained wp-container-core-group-is-layout-316810f1 wp-block-group-is-layout-constrained\" style=\"border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-left-radius:30px;border-bottom-right-radius:30px;background-color:#af9d8533;padding-top:40px;padding-right:var(--wp--preset--spacing--20);padding-bottom:40px;padding-left:var(--wp--preset--spacing--20)\">\n<p class=\"has-text-align-center has-accent-5-color has-text-color has-link-color has-molentta-font-family wp-elements-10 wp-block-paragraph\" style=\"font-size:clamp(21.536px, 1.346rem + ((1vw - 3.2px) * 1.403), 35px);\">Highlights<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.313), 17px);\">LIVING ROOM<br\/>OPEN KITCHEN<br\/>2 BEDROOMS<br\/>1 SHOWER ROOM + 1 SEPARATE TOILET<br\/>ENCLOSED TERRACE COMPLIANT<\/p>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"724\" src=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Plan-2026-11-Albizzias-1024x724.jpg\" alt=\"Plan 2026 11 Albizzias\" class=\"wp-image-38299\" srcset=\"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Plan-2026-11-Albizzias-1024x724.jpg 1024w, https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Plan-2026-11-Albizzias-300x212.jpg 300w, https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Plan-2026-11-Albizzias-768x543.jpg 768w, https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Plan-2026-11-Albizzias-1536x1086.jpg 1536w, https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Plan-2026-11-Albizzias.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group group-contact has-contrast-2-background-color has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"border-top-left-radius:40px;border-top-right-radius:40px;border-bottom-left-radius:40px;border-bottom-right-radius:40px;margin-top:var(--wp--preset--spacing--40);padding-top:50px;padding-bottom:50px\">\n<p class=\"has-text-align-center has-base-color has-text-color has-link-color wp-elements-11 wp-block-paragraph\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.313), 17px);text-transform:uppercase\">For further information or to visit, please contact<\/p>\n\n\n\n<p class=\"has-text-align-center has-base-color has-text-color has-link-color wp-elements-12 wp-block-paragraph\" style=\"font-size:clamp(18.959px, 1.185rem + ((1vw - 3.2px) * 1.15), 30px);font-style:normal;font-weight:700\"><a href=\"mailto:erika.laviolette@euronat.com\">erika.laviolette@euronat.com<\/a><br\/><a href=\"tel:330556732453\">+33 (0)5 56 73 24 53<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons btn-vert jaune animated fadeIn slow is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-663c8825 wp-block-buttons-is-layout-flex\" style=\"padding-top:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-button btn-print\"><a class=\"wp-block-button__link has-accent-5-background-color has-background wp-element-button\" href=\"#\" style=\"border-top-left-radius:100px;border-top-right-radius:100px;border-bottom-left-radius:100px;border-bottom-right-radius:100px;padding-top:14px;padding-right:32px;padding-bottom:14px;padding-left:32px;text-transform:uppercase\">print ad<\/a><\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":10641,"template":"","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_gt_ctv_global_id":"274","_gt_ctv_id_group":false,"inline_featured_image":false,"gt_fse_maillage_image":"https:\/\/www.euronat.com\/wp-content\/uploads\/2026\/01\/Euronatimmo-11-Albizzias-.jpg","gt_fse_maillage_titre":"11 Albizzias","gt_fse_maillage_alt":"Euronatimmo 11 Albizzias","gt_fse_maillage_resume":"","footnotes":""},"gt-vente-campings":[],"gt-vente-gammes":[],"gt-vente-options":[],"gt-vente-types":[288],"gt-vente-nombre-personnes":[],"gt-vente-nombre-chambres":[115],"gt-vente-nombre-sdb":[69],"gt-vente-superficie":[124],"gt-vente-prix":[491],"gt-vente-sous-titre":[305],"gt-vente-label-custom":[],"class_list":["post-10631","hebergement-vente","type-hebergement-vente","status-publish","has-post-thumbnail","hentry","gt-vente-types-mobile-homes","gt-vente-nombre-chambres-115","gt-vente-nombre-sdb-69","gt-vente-superficie-124","gt-vente-prix-43-000-e","gt-vente-sous-titre-otiny-830"],"_links":{"self":[{"href":"https:\/\/www.euronat.com\/en\/wp-json\/wp\/v2\/hebergement-vente\/10631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euronat.com\/en\/wp-json\/wp\/v2\/hebergement-vente"}],"about":[{"href":"https:\/\/www.euronat.com\/en\/wp-json\/wp\/v2\/types\/hebergement-vente"}],"version-history":[{"count":6,"href":"https:\/\/www.euronat.com\/en\/wp-json\/wp\/v2\/hebergement-vente\/10631\/revisions"}],"predecessor-version":[{"id":39330,"href":"https:\/\/www.euronat.com\/en\/wp-json\/wp\/v2\/hebergement-vente\/10631\/revisions\/39330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.euronat.com\/en\/wp-json\/wp\/v2\/media\/10641"}],"wp:attachment":[{"href":"https:\/\/www.euronat.com\/en\/wp-json\/wp\/v2\/media?parent=10631"}],"wp:term":[{"taxonomy":"gt-vente-campings","embeddable":true,"href":"https:\/\/www.euronat.com\/en\/wp-json\/wp\/v2\/gt-vente-campings?post=10631"},{"taxonomy":"gt-vente-gammes","embeddable":true,"href":"https:\/\/www.euronat.com\/en\/wp-json\/wp\/v2\/gt-vente-gammes?post=10631"},{"taxonomy":"gt-vente-options","embeddable":true,"href":"https:\/\/www.euronat.com\/en\/wp-json\/wp\/v2\/gt-vente-options?post=10631"},{"taxonomy":"gt-vente-types","embeddable":true,"href":"https:\/\/www.euronat.com\/en\/wp-json\/wp\/v2\/gt-vente-types?post=10631"},{"taxonomy":"gt-vente-nombre-personnes","embeddable":true,"href":"https:\/\/www.euronat.com\/en\/wp-json\/wp\/v2\/gt-vente-nombre-personnes?post=10631"},{"taxonomy":"gt-vente-nombre-chambres","embeddable":true,"href":"https:\/\/www.euronat.com\/en\/wp-json\/wp\/v2\/gt-vente-nombre-chambres?post=10631"},{"taxonomy":"gt-vente-nombre-sdb","embeddable":true,"href":"https:\/\/www.euronat.com\/en\/wp-json\/wp\/v2\/gt-vente-nombre-sdb?post=10631"},{"taxonomy":"gt-vente-superficie","embeddable":true,"href":"https:\/\/www.euronat.com\/en\/wp-json\/wp\/v2\/gt-vente-superficie?post=10631"},{"taxonomy":"gt-vente-prix","embeddable":true,"href":"https:\/\/www.euronat.com\/en\/wp-json\/wp\/v2\/gt-vente-prix?post=10631"},{"taxonomy":"gt-vente-sous-titre","embeddable":true,"href":"https:\/\/www.euronat.com\/en\/wp-json\/wp\/v2\/gt-vente-sous-titre?post=10631"},{"taxonomy":"gt-vente-label-custom","embeddable":true,"href":"https:\/\/www.euronat.com\/en\/wp-json\/wp\/v2\/gt-vente-label-custom?post=10631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}